{"id":166,"date":"2022-09-15T11:33:34","date_gmt":"2022-09-15T09:33:34","guid":{"rendered":"https:\/\/efis.parisnanterre.fr\/copa75\/?p=166"},"modified":"2022-09-16T15:22:30","modified_gmt":"2022-09-16T13:22:30","slug":"2-enjeux-relationnels","status":"publish","type":"post","link":"https:\/\/efis.parisnanterre.fr\/copa75\/2022\/09\/15\/2-enjeux-relationnels\/","title":{"rendered":"2 &#8211; Enjeux relationnels"},"content":{"rendered":"\n<p>La qualit\u00e9 des relations entre les professionnel.le.s de protection de l&rsquo;enfance et les personnes usag\u00e8res (enfants et adultes) est d\u00e9crite dans la litt\u00e9rature scientifique comme un \u00e9l\u00e9ment central de l&rsquo;efficacit\u00e9 des interventions socio-\u00e9ducatives (Buckley, Carr, &amp; Whelan, 2011; de Boer &amp; Coady, 2007&nbsp;; Euillet, Kettani &amp; Join-Lambert, 2018&nbsp;; Tillard, Val\u00e9rie &amp; Rurka 2016 ). De plus, les recherches ont \u00e9galement montr\u00e9 que la relation interindividuelle entre le professionnel et le parent, bas\u00e9e sur des repr\u00e9sentations r\u00e9ciproques et positives influence le rapport et la perception des parents vis-\u00e0-vis du syst\u00e8me entier de l\u2019aide \u00e0 l\u2019enfance (Buckley et al., 2011; Gladstone et al., 2012&nbsp;; Rurka 2008&nbsp;; Spratt &amp; Callan, 2004).<\/p>\n\n\n\n<p>La reconnaissance, le respect et la r\u00e9ciprocit\u00e9 constituent une base pour un engagement \u00e9thique avec les personnes \u00ab&nbsp;non volontaires&nbsp;\u00bb (Turney, 2012). Le caract\u00e8re contraignant et impos\u00e9 des mesures \u00e9ducatives ou du placement sous menace de la loi rend les relations de pouvoir extr\u00eamement d\u00e9s\u00e9quilibr\u00e9es entre les familles et les travailleurs sociaux. La sur-responsabilisation des parents quant aux difficult\u00e9s rencontr\u00e9es par l\u2019enfant et la non-prise en compte du contexte dans l\u2019\u00e9ducation de l\u2019enfant \u00e9volue, contribue \u00e0 stigmatiser les parents. Cette stigmatisation est renforc\u00e9e lorsque les parents et les travailleurs sociaux ne partagent pas le m\u00eame point de vue sur les responsabilit\u00e9s \u00e9ducatives quant aux risques ou dangers identifi\u00e9s chez l\u2019enfant, accompagn\u00e9 ou accueilli en protection de l\u2019enfance. Au titre d\u2019une prise de conscience, les travailleurs sociaux exigent des parents qu&rsquo;ils acceptent la responsabilit\u00e9 des risques identifi\u00e9s. Les recherches l\u2019ont fait ressortir lorsqu\u2019il s\u2019agit des choix \u00e9ducatifs des parents (Rurka et al. 2009) et lorsqu\u2019il s\u2019agit d\u2019intervenir dans le contexte de violences domestiques (Bourassa et al. 2008&nbsp;; Stanley et al., 2011). Cette diff\u00e9rence des points de vue peut \u00e9galement porter sur la mani\u00e8re de rem\u00e9dier aux difficult\u00e9s de l\u2019enfant. Cela rend les interactions entre eux difficiles, voire conflictuelles. \u00c9tant usagers des services sociaux, les parents t\u00e9moignent souvent du sentiment de honte (Gaulejac, 1996) qui s\u2019ajoute \u00e0 des violences institutionnelles quotidiennes d\u00e9coulant de leurs statuts d\u2019\u00ab&nbsp;<em>acteur faible<\/em>&nbsp;\u00bb (Payet, Guliani, Laforgue, 2008). Dans le contexte de violences domestiques, les travailleurs sociaux eux-m\u00eames peuvent \u00eatre d\u00e9chir\u00e9s entre la consid\u00e9ration des m\u00e8res comme des victimes de violence, tout en leur reprochant de ne pas prot\u00e9ger leurs enfants de l&rsquo;exposition \u00e0 cette violence (Lapierre et C\u00f4t\u00e9, 2011). La sur-repr\u00e9sentation des parents appara\u00eet lorsque la relation parent-enfant est analys\u00e9e d\u2019une mani\u00e8re limit\u00e9e et limitative, sans une prise en compte du contexte de vie de l\u2019enfant, notamment des conditions mat\u00e9rielles et des ressources disponibles, y compris chez des familles de classe moyenne. Les facteurs sociaux de danger (par exemple logement, ins\u00e9curit\u00e9 alimentaire, manque de services ad\u00e9quats) sont minimis\u00e9s dans l&rsquo;interpr\u00e9tation du danger av\u00e9r\u00e9 ou potentiel. Pourtant, les recherches internationales ont montr\u00e9 que la n\u00e9gligence d\u00e9coule d&rsquo;interactions entre plusieurs facteurs. Elle se manifeste sur le plan de la relation parent-enfant o\u00f9 le parent, pour diff\u00e9rentes raisons, y compris contextuelles, ne semble pas \u00eatre disponible pour r\u00e9pondre aux besoins de l\u2019enfant, mais aussi sur le plan social, car les parents concern\u00e9s sont souvent isol\u00e9s (Lacharit\u00e9, \u00c9thier &amp; Nolin, 2006). Cet isolement social est l\u2019un des facteurs de risque qui limite significativement les ressources et les capacit\u00e9s des parents \u00e0 r\u00e9pondre aux besoins de l\u2019enfant et aux situations \u00e9ducatives, y compris les situations de crise.<\/p>\n\n\n\n<p>La participation des parents implique \u00e9galement le fait d\u2019\u00eatre associ\u00e9e \u00e0 l\u2019\u00e9ducation de l\u2019enfant en situation de placement. Cependant, lorsque les relations entre le professionnel et le parent sont tendues, la mise \u00e0 distance du parent peut conduire \u00e0 la conclusion de sa non-coop\u00e9ration avec les professionnel.le.s. En cons\u00e9quence, il serait plus rarement associ\u00e9 par les professionnel.le.s aux d\u00e9cisions li\u00e9es \u00e0 l\u2019\u00e9ducation de l\u2019enfant. Les parents attendent le contraire, \u00e0 savoir que le professionnel va les aider \u00e0 maintenir les liens avec leurs enfants accueillis temporairement en institution ou en famille d\u2019accueil. Cela se traduit et manifeste par l\u2019information r\u00e9guli\u00e8re et continue des parents sur la vie quotidienne de l\u2019enfant dans son lieu de r\u00e9sidence, par l\u2019envoi des photos de leurs enfants, et par la facilitation des relations avec les parents d&rsquo;accueil. L&#8217;empathie devient cruciale dans ces situations. D&rsquo;abord, pour que le retrait d&rsquo;un enfant ne soit pas une punition pour les parents qui luttent contre nombreux facteurs qui les placent en situation de vuln\u00e9rabilit\u00e9, ind\u00e9pendamment de leur volont\u00e9.<\/p>\n\n\n\n<p>Depuis l\u2019institutionnalisation du travail social, ce dernier remplit \u00e0 la fois une mission de contr\u00f4le social et d\u2019aide. Ce paradoxe fondateur du travail social constitue un dilemme pour les travailleur.ses sociaux.ales dont l\u2019intervention peut avoir un caract\u00e8re punitif, tout en poursuivant le but de d\u00e9velopper le pouvoir d\u2019agir des parents et de renforcer l\u2019autorit\u00e9 parentale sans porter pr\u00e9judice \u00e0 l&rsquo;enfant. De plus, les professionnel.le.s sont amen\u00e9.e.s \u00e0 remplir la mission de protection de l\u2019enfance dans des contextes d\u2019incertitudes, des faits suppos\u00e9s et non av\u00e9r\u00e9s. Dans ce contexte, l&rsquo;absence d&rsquo;engagement parental peut renforcer le caract\u00e8re plus coercitif de la part des praticien.ne.s qui ont la responsabilit\u00e9 de prot\u00e9ger l\u2019enfant.<\/p>\n\n\n\n<p>L\u2019empathie, le dialogue autour du pouvoir institutionnel et le pouvoir d\u2019agir de chaque acteur facilitent la participation et rendent les processus de prise de d\u00e9cisions plus transparents et ouverts. Car pour que la participation soit effective, elle n\u00e9cessite que les participant.e.s s\u2019\u00e9coutent, se r\u00e9pondent, r\u00e9fl\u00e9chissent et agissent ensemble, sans forc\u00e9ment r\u00e9aliser les m\u00eames t\u00e2ches. Le dialogue sur le pouvoir ne signifie pas que les travailleur.se.s sociaux.ales fuient la responsabilit\u00e9 de prendre des d\u00e9cisions. Au contraire, l&rsquo;utilisation d&rsquo;un tel dialogue rel\u00e8ve de la responsabilit\u00e9 des travailleurs sociaux afin de promouvoir la participation des parents et de prendre des d\u00e9cisions sur la base de leur connaissance et exp\u00e9rience. Le dialogue bas\u00e9 sur le principe de r\u00e9ciprocit\u00e9 peut contribuer \u00e0 rendre la pratique moins anxieuse, plus \u00e9quilibr\u00e9e et r\u00e9fl\u00e9chie et potentiellement moins oppressive (Turney, 2012).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La qualit\u00e9 des relations entre les professionnel.le.s de protection de l&rsquo;enfance et les personnes usag\u00e8res (enfants et adultes) est d\u00e9crite dans la litt\u00e9rature scientifique comme un \u00e9l\u00e9ment central de l&rsquo;efficacit\u00e9 des interventions socio-\u00e9ducatives (Buckley, Carr, &amp; Whelan, 2011; de Boer &amp; Coady, 2007&nbsp;; Euillet, Kettani &amp; Join-Lambert, 2018&nbsp;; Tillard, Val\u00e9rie &amp; Rurka 2016 ). De&#8230;<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[6],"tags":[],"coauthors":[2],"class_list":["post-166","post","type-post","status-publish","format-standard","hentry","category-partie1"],"taxonomy_info":{"category":[{"value":6,"label":"Partie I - Outils pour penser la participation"}]},"featured_image_src_large":false,"author_info":{"display_name":"admin","author_link":"https:\/\/efis.parisnanterre.fr\/copa75\/author\/scarella\/"},"comment_info":0,"category_info":[{"term_id":6,"name":"Partie I - Outils pour penser la participation","slug":"partie1","term_group":0,"term_taxonomy_id":6,"taxonomy":"category","description":"","parent":12,"count":8,"filter":"raw","cat_ID":6,"category_count":8,"category_description":"","cat_name":"Partie I - Outils pour penser la participation","category_nicename":"partie1","category_parent":12}],"tag_info":false,"_links":{"self":[{"href":"https:\/\/efis.parisnanterre.fr\/copa75\/wp-json\/wp\/v2\/posts\/166","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/efis.parisnanterre.fr\/copa75\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/efis.parisnanterre.fr\/copa75\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/efis.parisnanterre.fr\/copa75\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/efis.parisnanterre.fr\/copa75\/wp-json\/wp\/v2\/comments?post=166"}],"version-history":[{"count":1,"href":"https:\/\/efis.parisnanterre.fr\/copa75\/wp-json\/wp\/v2\/posts\/166\/revisions"}],"predecessor-version":[{"id":167,"href":"https:\/\/efis.parisnanterre.fr\/copa75\/wp-json\/wp\/v2\/posts\/166\/revisions\/167"}],"wp:attachment":[{"href":"https:\/\/efis.parisnanterre.fr\/copa75\/wp-json\/wp\/v2\/media?parent=166"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/efis.parisnanterre.fr\/copa75\/wp-json\/wp\/v2\/categories?post=166"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/efis.parisnanterre.fr\/copa75\/wp-json\/wp\/v2\/tags?post=166"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/efis.parisnanterre.fr\/copa75\/wp-json\/wp\/v2\/coauthors?post=166"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}